{"id":3097,"date":"2014-07-07T09:35:47","date_gmt":"2014-07-07T12:35:47","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/prae\/?p=3097"},"modified":"2014-07-07T09:35:47","modified_gmt":"2014-07-07T12:35:47","slug":"informacao-nutricional-do-cardapio-de-segunda-feira-0707","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/prae\/2014\/07\/07\/informacao-nutricional-do-cardapio-de-segunda-feira-0707\/","title":{"rendered":"Informa\u00e7\u00e3o Nutricional do Card\u00e1pio de Segunda-Feira (07\/07)"},"content":{"rendered":"<p><a href=\"https:\/\/wp.ufpel.edu.br\/prae\/files\/2014\/07\/Informa\u00e7\u00e3o-Nutricional.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3098\" src=\"https:\/\/wp.ufpel.edu.br\/prae\/files\/2014\/07\/Informa\u00e7\u00e3o-Nutricional.jpg\" alt=\"Informa\u00e7\u00e3o Nutricional\" width=\"907\" height=\"1367\" srcset=\"https:\/\/wp.ufpel.edu.br\/prae\/files\/2014\/07\/Informa\u00e7\u00e3o-Nutricional.jpg 907w, https:\/\/wp.ufpel.edu.br\/prae\/files\/2014\/07\/Informa\u00e7\u00e3o-Nutricional-105x159.jpg 105w, https:\/\/wp.ufpel.edu.br\/prae\/files\/2014\/07\/Informa\u00e7\u00e3o-Nutricional-210x318.jpg 210w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":229,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38889],"tags":[],"class_list":["post-3097","post","type-post","status-publish","format-standard","hentry","category-restaurante-universitario"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/prae\/wp-json\/wp\/v2\/posts\/3097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/prae\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/prae\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/prae\/wp-json\/wp\/v2\/users\/229"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/prae\/wp-json\/wp\/v2\/comments?post=3097"}],"version-history":[{"count":1,"href":"https:\/\/wp.ufpel.edu.br\/prae\/wp-json\/wp\/v2\/posts\/3097\/revisions"}],"predecessor-version":[{"id":3099,"href":"https:\/\/wp.ufpel.edu.br\/prae\/wp-json\/wp\/v2\/posts\/3097\/revisions\/3099"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/prae\/wp-json\/wp\/v2\/media?parent=3097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/prae\/wp-json\/wp\/v2\/categories?post=3097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/prae\/wp-json\/wp\/v2\/tags?post=3097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}