{"id":7822,"date":"2023-04-06T21:45:30","date_gmt":"2023-04-07T00:45:30","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/ppgs\/?p=7822"},"modified":"2026-04-20T13:17:22","modified_gmt":"2026-04-20T16:17:22","slug":"metamorfoses-da-sociologia-o-lugar-das-ideias-fora-do-lugar-com-marcos-lacerda","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/ppgs\/2023\/04\/06\/metamorfoses-da-sociologia-o-lugar-das-ideias-fora-do-lugar-com-marcos-lacerda\/","title":{"rendered":"Metamorfoses da Sociologia: O lugar das ideias fora do lugar, com Marcos Lacerda"},"content":{"rendered":"<p>Marcos Lacerda, p\u00f3s-doutorando no PPGS, participou do programa e podcast Rep\u00fablica de Ideias, do Ateli\u00ea de Humanidades, falando sobre o tema &#8220;Metamorfoses da Sociologia: O lugar das ideias fora do lugar&#8221;. A fala traz algumas de suas contribui\u00e7\u00f5es para o projeto Metamorfoses da Sociologia, apoiado pelo CNPq. Marcos traz seu trabalho sobre a tradi\u00e7\u00e3o de pensamento cr\u00edtico brasileira a partir de Antonio Candido, Roberto Schwarz e Paulo Arantes, entre outros. Tal escola de pensamento \u00e9 apresentada como uma poss\u00edvel perspectiva para entender as crises da sociedade contempor\u00e2nea, incluindo os desafios das Ci\u00eancias Sociais e Humanas, a partir de uma posi\u00e7\u00e3o perif\u00e9rica no sistema global. O v\u00eddeo est\u00e1 dispon\u00edvel no seguinte link:<a href=\"https:\/\/www.youtube.com\/watch?v=K3O8q_XrNHM\"> https:\/\/www.youtube.com\/watch?v=K3O8q_XrNHM. <\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/ppgs\/files\/2023\/04\/image-1.png?ssl=1\"><img data-recalc-dims=\"1\" data-attachment-id=\"7823\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/ppgs\/2023\/04\/06\/metamorfoses-da-sociologia-o-lugar-das-ideias-fora-do-lugar-com-marcos-lacerda\/image-1-4\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/ppgs\/files\/2023\/04\/image-1.png?fit=1195%2C591&amp;ssl=1\" data-orig-size=\"1195,591\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image (1)\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/ppgs\/files\/2023\/04\/image-1.png?fit=400%2C198&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/ppgs\/files\/2023\/04\/image-1.png?fit=1024%2C506&amp;ssl=1\" class=\"aligncenter wp-image-7823\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/ppgs\/files\/2023\/04\/image-1.png?resize=577%2C285&#038;ssl=1\" alt=\"\" width=\"577\" height=\"285\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/ppgs\/files\/2023\/04\/image-1.png?resize=1024%2C506&amp;ssl=1 1024w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/ppgs\/files\/2023\/04\/image-1.png?resize=400%2C198&amp;ssl=1 400w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/ppgs\/files\/2023\/04\/image-1.png?resize=768%2C380&amp;ssl=1 768w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/ppgs\/files\/2023\/04\/image-1.png?w=1195&amp;ssl=1 1195w\" sizes=\"(max-width: 577px) 100vw, 577px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marcos Lacerda, p\u00f3s-doutorando no PPGS, participou do programa e podcast Rep\u00fablica de Ideias, do Ateli\u00ea de Humanidades, falando sobre o tema &#8220;Metamorfoses da Sociologia: O lugar das ideias fora do lugar&#8221;. A fala traz algumas de suas contribui\u00e7\u00f5es para o projeto Metamorfoses da Sociologia, apoiado pelo CNPq. Marcos traz seu trabalho sobre a tradi\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":396,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[18],"tags":[],"class_list":["post-7822","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9dZ0f-22a","jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgs\/wp-json\/wp\/v2\/posts\/7822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgs\/wp-json\/wp\/v2\/users\/396"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgs\/wp-json\/wp\/v2\/comments?post=7822"}],"version-history":[{"count":2,"href":"https:\/\/wp.ufpel.edu.br\/ppgs\/wp-json\/wp\/v2\/posts\/7822\/revisions"}],"predecessor-version":[{"id":7828,"href":"https:\/\/wp.ufpel.edu.br\/ppgs\/wp-json\/wp\/v2\/posts\/7822\/revisions\/7828"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgs\/wp-json\/wp\/v2\/media?parent=7822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgs\/wp-json\/wp\/v2\/categories?post=7822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgs\/wp-json\/wp\/v2\/tags?post=7822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}