{"id":871,"date":"2023-03-18T14:51:08","date_gmt":"2023-03-18T17:51:08","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/?p=871"},"modified":"2023-03-18T14:53:48","modified_gmt":"2023-03-18T17:53:48","slug":"homologacao-preliminar-da-inscricoes-edital-81-2023","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/2023\/03\/18\/homologacao-preliminar-da-inscricoes-edital-81-2023\/","title":{"rendered":"Homologa\u00e7\u00e3o preliminar das inscri\u00e7\u00f5es &#8211; Edital 81\/2023"},"content":{"rendered":"<p><a href=\"https:\/\/wp.ufpel.edu.br\/ppgmpar\/files\/2023\/03\/Homologacao-preliminar-inscricoes-Edital-81-2023.pdf\">Homologa\u00e7\u00e3o preliminar inscri\u00e7\u00f5es &#8211; Edital 81-2023<\/a><\/p>\n<p>Os recurso ao resultado da homologa\u00e7\u00e3o das candidaturas e de qualquer uma das fases da avalia\u00e7\u00e3o deve ser encaminhada por escrito para a Comiss\u00e3o de Avalia\u00e7\u00e3o no prazo de at\u00e9 72 horas contadas a partir da divulga\u00e7\u00e3o dos resultados. Os documentos ausentes podem ser enviados por e-mail: <a href=\"mailto:parasitologia@ufpel.edu.br\" target=\"_blank\" rel=\"noopener\">parasitologia@ufpel.edu.br<\/a>\u00a0at\u00e9 o dia 21 de mar\u00e7o as 15 Hs. A an\u00e1lise dos recursos ser\u00e1 feita pelo Colegiado do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Microbiologia e Parasitologia, levando em conta a aplica\u00e7\u00e3o dos crit\u00e9rios dispostos neste Edital.<\/p>\n<p>A listagem definitiva de candidatos homologados ser\u00e1 divulgado na p\u00e1gina do programa (<a href=\"https:\/\/wp.ufpel.edu.br\/ppgmpar\/\" target=\"_blank\" rel=\"noopener\">https:\/\/wp.ufpel.edu.br\/ppgmpar\/<\/a>) no dia 21\u00a0de mar\u00e7o as 20\u00a0Hs.<\/p>\n<p>O cronograma de provas poder\u00e1 sofrer altera\u00e7\u00f5es com aviso pr\u00e9vio aos candidatos homologados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Homologa\u00e7\u00e3o preliminar inscri\u00e7\u00f5es &#8211; Edital 81-2023 Os recurso ao resultado da homologa\u00e7\u00e3o das candidaturas e de qualquer uma das fases da avalia\u00e7\u00e3o deve ser encaminhada por escrito para a Comiss\u00e3o de Avalia\u00e7\u00e3o no prazo de at\u00e9 72 horas contadas a partir da divulga\u00e7\u00e3o dos resultados. Os documentos ausentes podem ser enviados por e-mail: parasitologia@ufpel.edu.br\u00a0at\u00e9 o [&hellip;]<\/p>\n","protected":false},"author":951,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-871","post","type-post","status-publish","format-standard","hentry","category-noticias"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/wp-json\/wp\/v2\/posts\/871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/wp-json\/wp\/v2\/users\/951"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/wp-json\/wp\/v2\/comments?post=871"}],"version-history":[{"count":3,"href":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/wp-json\/wp\/v2\/posts\/871\/revisions"}],"predecessor-version":[{"id":876,"href":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/wp-json\/wp\/v2\/posts\/871\/revisions\/876"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/wp-json\/wp\/v2\/media?parent=871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/wp-json\/wp\/v2\/categories?post=871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgmpar\/wp-json\/wp\/v2\/tags?post=871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}