{"id":714,"date":"2017-04-27T21:04:35","date_gmt":"2017-04-28T00:04:35","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/ppgemat\/?p=714"},"modified":"2017-04-29T01:57:26","modified_gmt":"2017-04-29T04:57:26","slug":"ufpel-sedia-xv-seminario-tematico-cadernos-escolares-de-alunos-e-professores-e-a-historia-da-educacao-matematica-1890-1990","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/ppgemat\/2017\/04\/27\/ufpel-sedia-xv-seminario-tematico-cadernos-escolares-de-alunos-e-professores-e-a-historia-da-educacao-matematica-1890-1990\/","title":{"rendered":"De 29\/abril a 01\/maio UFPel sedia XV Semin\u00e1rio Tem\u00e1tico em hist\u00f3ria da Educa\u00e7\u00e3o Matem\u00e1tica"},"content":{"rendered":"<h3> <\/h3>\n<p><TABLE width=\"90%\"><TR><TD><br \/>\n<strong>XV Semin\u00e1rio Tem\u00e1tico: Cadernos escolares de alunos e professores e a hist\u00f3ria da Educa\u00e7\u00e3o Matem\u00e1tica, 1890 &#8211; 1990 <\/strong><\/p>\n<p>Data: 29\/abr, 30\/abr e 01\/mai<\/p>\n<p>Local: Faculdade de Direito da UFPel <\/p>\n<p>Promo\u00e7\u00e3o: PPGEMAT\/UFPel e PPG em Educa\u00e7\u00e3o Matem\u00e1tica\/UFRGS<\/p>\n<p>Estar\u00e3o presentes v\u00e1rios grupos de pesquisa de cursos de p\u00f3s-gradua\u00e7\u00e3o de cerca de 20 estados brasileiros, al\u00e9m de parceiros internacionais interessados na hist\u00f3ria da Educa\u00e7\u00e3o Matem\u00e1tica.<\/p>\n<p>As atividades plen\u00e1rias ser\u00e3o transmitidas em tempo real pelo link:<br \/>\n<a href=\"https:\/\/conferenciaweb.rnp.br\/webconf\/joao-2\">https:\/\/conferenciaweb.rnp.br\/webconf\/joao-2<\/a><\/p>\n<p>Leia  <a href=\"https:\/\/wp.ufpel.edu.br\/ppgemat\/files\/2017\/04\/Tutorial-de-acesso.pdf\"> <strong>TUTORIAL DE ACESSO<\/strong> <\/a> com orienta\u00e7\u00f5es de como acessar a webconfer\u00eancia do evento.<\/p>\n<p>Consulte a programa\u00e7\u00e3o, clicando <a href=\"http:\/\/xvseminariotematico.paginas.ufsc.br\"> aqui <\/a><\/p>\n<p><img src=\"https:\/\/wp.ufpel.edu.br\/ppgemat\/files\/2017\/04\/seminario-1.jpg\" \/><\/p>\n<p><\/TD><\/TR><\/TABLE><br \/>\n<H3> <\/H3><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XV Semin\u00e1rio Tem\u00e1tico: Cadernos escolares de alunos e professores e a hist\u00f3ria da Educa\u00e7\u00e3o Matem\u00e1tica, 1890 &#8211; 1990 Data: 29\/abr, 30\/abr e 01\/mai Local: Faculdade de Direito da UFPel Promo\u00e7\u00e3o: PPGEMAT\/UFPel e PPG em Educa\u00e7\u00e3o Matem\u00e1tica\/UFRGS Estar\u00e3o presentes v\u00e1rios grupos de pesquisa de cursos de p\u00f3s-gradua\u00e7\u00e3o de cerca de 20 estados brasileiros, al\u00e9m de parceiros [&hellip;]<\/p>\n","protected":false},"author":617,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-714","post","type-post","status-publish","format-standard","hentry","category-noticias"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgemat\/wp-json\/wp\/v2\/posts\/714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgemat\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgemat\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgemat\/wp-json\/wp\/v2\/users\/617"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgemat\/wp-json\/wp\/v2\/comments?post=714"}],"version-history":[{"count":10,"href":"https:\/\/wp.ufpel.edu.br\/ppgemat\/wp-json\/wp\/v2\/posts\/714\/revisions"}],"predecessor-version":[{"id":726,"href":"https:\/\/wp.ufpel.edu.br\/ppgemat\/wp-json\/wp\/v2\/posts\/714\/revisions\/726"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgemat\/wp-json\/wp\/v2\/media?parent=714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgemat\/wp-json\/wp\/v2\/categories?post=714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgemat\/wp-json\/wp\/v2\/tags?post=714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}