{"id":1256,"date":"2016-12-27T11:55:27","date_gmt":"2016-12-27T13:55:27","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/mestradoartesvisuais\/?p=1256"},"modified":"2016-12-27T11:55:27","modified_gmt":"2016-12-27T13:55:27","slug":"selecao-de-bolsistas-programa-de-bolsas-de-mestrado","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/ppgartes\/2016\/12\/27\/selecao-de-bolsistas-programa-de-bolsas-de-mestrado\/","title":{"rendered":"SELE\u00c7\u00c3O DE BOLSISTAS &#8211; PROGRAMA DE BOLSAS DE MESTRADO"},"content":{"rendered":"<p>O Mestrado em Artes Visuais torna p\u00fablico o presente Edital para os alunos regularmente matriculados no curso interessados em participar da SELE\u00c7\u00c3O DE BOLSAS DE MESTRADO\/2017, conforme os requisitos e condi\u00e7\u00f5es fixados neste Edital. As inscri\u00e7\u00f5es estar\u00e3o abertas de <strong>08 e 09 de fevereiro de 2017<\/strong>, toda a documenta\u00e7\u00e3o dever\u00e1 ser encaminhada \u00e0 secretaria do PPGAV (c\u00f3pias simples, impressas).<\/p>\n<p><a href=\"https:\/\/wp.ufpel.edu.br\/ppgartes\/files\/2016\/12\/EDITAL-04-2016_selecao-de-bolsistas_PPGAV.pdf\">EDITAL 04-2016_sele\u00e7\u00e3o de bolsistas_PPGAV<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Mestrado em Artes Visuais torna p\u00fablico o presente Edital para os alunos regularmente matriculados no curso interessados em participar da SELE\u00c7\u00c3O DE BOLSAS DE MESTRADO\/2017, conforme os requisitos e condi\u00e7\u00f5es fixados neste Edital. As inscri\u00e7\u00f5es estar\u00e3o abertas de 08 e 09 de fevereiro de 2017, toda a documenta\u00e7\u00e3o dever\u00e1 ser encaminhada \u00e0 secretaria do [&hellip;]<\/p>\n","protected":false},"author":1258,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1256","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgartes\/wp-json\/wp\/v2\/posts\/1256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgartes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgartes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgartes\/wp-json\/wp\/v2\/users\/1258"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgartes\/wp-json\/wp\/v2\/comments?post=1256"}],"version-history":[{"count":0,"href":"https:\/\/wp.ufpel.edu.br\/ppgartes\/wp-json\/wp\/v2\/posts\/1256\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/ppgartes\/wp-json\/wp\/v2\/media?parent=1256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgartes\/wp-json\/wp\/v2\/categories?post=1256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ppgartes\/wp-json\/wp\/v2\/tags?post=1256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}