{"id":4460,"date":"2025-11-21T18:33:51","date_gmt":"2025-11-21T21:33:51","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/leppais\/?p=4460"},"modified":"2025-11-21T18:33:51","modified_gmt":"2025-11-21T21:33:51","slug":"1a-mostra-antropoetica-de-filmes-etnograficos","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/","title":{"rendered":"1\u00aa Mostra Antropo\u00e9tica de Filmes Etnogr\u00e1ficos"},"content":{"rendered":"\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div data-carousel-extra='{&quot;blog_id&quot;:939,&quot;permalink&quot;:&quot;https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/&quot;}' id='gallery-1' class='gallery galleryid-4460 gallery-columns-3 gallery-size-large'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/1\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"730\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?fit=584%2C730&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?resize=768%2C960&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"4461\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/1\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?fit=1080%2C1350&amp;ssl=1\" data-orig-size=\"1080,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"1\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?fit=240%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?fit=584%2C730&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/2\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"730\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/2.png?fit=584%2C730&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/2.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/2.png?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/2.png?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/2.png?resize=768%2C960&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"4462\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/2\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/2.png?fit=1080%2C1350&amp;ssl=1\" data-orig-size=\"1080,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"2\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/2.png?fit=240%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/2.png?fit=584%2C730&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/3\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"730\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/3.png?fit=584%2C730&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/3.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/3.png?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/3.png?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/3.png?resize=768%2C960&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"4463\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/3\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/3.png?fit=1080%2C1350&amp;ssl=1\" data-orig-size=\"1080,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"3\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/3.png?fit=240%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/3.png?fit=584%2C730&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/4\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"730\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/4.png?fit=584%2C730&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/4.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/4.png?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/4.png?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/4.png?resize=768%2C960&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"4464\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/4\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/4.png?fit=1080%2C1350&amp;ssl=1\" data-orig-size=\"1080,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"4\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/4.png?fit=240%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/4.png?fit=584%2C730&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/5\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"730\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/5.png?fit=584%2C730&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/5.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/5.png?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/5.png?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/5.png?resize=768%2C960&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"4465\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/5\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/5.png?fit=1080%2C1350&amp;ssl=1\" data-orig-size=\"1080,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"5\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/5.png?fit=240%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/5.png?fit=584%2C730&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/6\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"730\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/6.png?fit=584%2C730&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/6.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/6.png?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/6.png?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/6.png?resize=768%2C960&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"4466\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/6\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/6.png?fit=1080%2C1350&amp;ssl=1\" data-orig-size=\"1080,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"6\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/6.png?fit=240%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/6.png?fit=584%2C730&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/7\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"730\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/7.png?fit=584%2C730&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/7.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/7.png?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/7.png?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/7.png?resize=768%2C960&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"4467\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/7\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/7.png?fit=1080%2C1350&amp;ssl=1\" data-orig-size=\"1080,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"7\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/7.png?fit=240%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/7.png?fit=584%2C730&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/8\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"730\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/8.png?fit=584%2C730&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/8.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/8.png?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/8.png?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/8.png?resize=768%2C960&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"4468\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/8\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/8.png?fit=1080%2C1350&amp;ssl=1\" data-orig-size=\"1080,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"8\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/8.png?fit=240%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/8.png?fit=584%2C730&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/9\/'><img loading=\"lazy\" decoding=\"async\" width=\"584\" height=\"730\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/9.png?fit=584%2C730&amp;ssl=1\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/9.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/9.png?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/9.png?resize=819%2C1024&amp;ssl=1 819w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/9.png?resize=768%2C960&amp;ssl=1 768w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" data-attachment-id=\"4469\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/attachment\/9\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/9.png?fit=1080%2C1350&amp;ssl=1\" data-orig-size=\"1080,1350\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"9\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/9.png?fit=240%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/9.png?fit=584%2C730&amp;ssl=1\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Em sua primeira edi\u00e7\u00e3o, esta Mostra conta com exibi\u00e7\u00e3o de filmes etnogr\u00e1ficos multissituada e debates online, estreitando as conex\u00f5es entre realizadores no campo da antropologia.<\/p>\n<p>O evento conta com a participa\u00e7\u00e3o das seguintes universidades e laborat\u00f3rios: Laborat\u00f3rio de Ensino, Pesquisa e Produ\u00e7\u00e3o em Antropologia da Imagem e do Som (LEPPAIS\/UFPel), Projeto de extens\u00e3o Hist\u00f3rias de Quilombo (Unila), Laborat\u00f3rio das Mem\u00f3rias e das Pr\u00e1ticas Cotidianas (LABOME UVA), Laborat\u00f3rio do Filme Etnogr\u00e1fico (LAB UFF) e Laborat\u00f3rio de Antropologia, Linguagens e Saberes (LALiS\/UFU).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em sua primeira edi\u00e7\u00e3o, esta Mostra conta com exibi\u00e7\u00e3o de filmes etnogr\u00e1ficos multissituada e debates online, estreitando as conex\u00f5es entre realizadores no campo da antropologia. O evento conta com a participa\u00e7\u00e3o das seguintes universidades e laborat\u00f3rios: Laborat\u00f3rio de Ensino, Pesquisa &hellip; <a href=\"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/\">Continue lendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":641,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-4460","post","type-post","status-publish","format-standard","hentry","category-noticias"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/payVYo-19W","jetpack-related-posts":[{"id":4474,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/28\/1a-mostra-antropoeticas-de-filmes-etnograficos-no-cehus\/","url_meta":{"origin":4460,"position":0},"title":"1\u00aa Mostra Antropo\u00e9ticas de Filmes Etnogr\u00e1ficos no Cehus","author":"antropologia","date":"28\/11\/2025","format":false,"excerpt":"\u00a0 No dia 27 de Novembro de 2025, ocorreu a 1\u00aa Mostra Antropo\u00e9ticas de Filmes Etnogr\u00e1ficos, no campus do Cehus da Ufpel. A mostra ocorreu das 14h \u00e0s 19h presencial e online em conjunto a parceiros, tendo direito at\u00e9 a pipoca para ver a mostra. Os filmes foram seguidos por\u2026","rel":"","context":"Em &quot;Atividades&quot;","block_context":{"text":"Atividades","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/atividades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":1789,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2018\/10\/25\/convite-mostra-de-filmes-etnograficos-os-seres-da-mata-e-sua-vida-como-pessoas\/","url_meta":{"origin":4460,"position":1},"title":"Convite: Mostra de Filmes Etnogr\u00e1ficos &#8211; Os seres da mata e sua vida como pessoas","author":"antropologia","date":"25\/10\/2018","format":false,"excerpt":"","rel":"","context":"Em &quot;Convite&quot;","block_context":{"text":"Convite","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/convite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":3212,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2020\/07\/21\/convite-iii-mostra-arandu-de-filmes-etnograficos-2020\/","url_meta":{"origin":4460,"position":2},"title":"Convite &#8211; III MOSTRA ARANDU DE FILMES ETNOGRAFICOS 2020","author":"antropologia","date":"21\/07\/2020","format":false,"excerpt":"III Mostra Arandu de Filmes Etnogr\u00e1ficos 2020 \"Antropologia e Sociedade - Compartilhando Saberes\" Inscri\u00e7\u00f5es abertas pelo link at\u00e9 o dia 31\/08 Aguardamos sua inscri\u00e7\u00e3o! Formul\u00e1rio https:\/\/forms.gle\/77pnHaaRyREYKTW18 Links para as Mostras anteriores: https:\/\/arandumostra.wordpress.com\/ Link para nossa p\u00e1gina eletr\u00f4nica: https:\/\/avaedoc.blog\/ Mais informa\u00e7\u00f5es (PDF)","rel":"","context":"Em &quot;Convite&quot;","block_context":{"text":"Convite","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/convite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2020\/07\/arandu.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2020\/07\/arandu.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2020\/07\/arandu.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2020\/07\/arandu.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2020\/07\/arandu.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1849,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2018\/11\/21\/convite-mostra-de-filmes-etnograficos-com-o-filme-voz-das-mulheres-indigenas\/","url_meta":{"origin":4460,"position":3},"title":"Convite: Mostra de Filmes Etnogr\u00e1ficos com o filme &#8220;Voz das Mulheres Ind\u00edgenas&#8221;","author":"antropologia","date":"21\/11\/2018","format":false,"excerpt":"","rel":"","context":"Em &quot;Convite&quot;","block_context":{"text":"Convite","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/convite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1570,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2018\/06\/07\/iii-mostra-de-filmes-etnograficos\/","url_meta":{"origin":4460,"position":4},"title":"III Mostra de Filmes Etnogr\u00e1ficos","author":"antropologia","date":"07\/06\/2018","format":false,"excerpt":"","rel":"","context":"Em &quot;Atividades&quot;","block_context":{"text":"Atividades","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/atividades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/06\/iii-mostra-de-filmes-etnograficos_v6.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/06\/iii-mostra-de-filmes-etnograficos_v6.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/06\/iii-mostra-de-filmes-etnograficos_v6.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/06\/iii-mostra-de-filmes-etnograficos_v6.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/06\/iii-mostra-de-filmes-etnograficos_v6.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1439,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2018\/04\/18\/el-candombe-mostra-fotografica-de-lisandro-moura\/","url_meta":{"origin":4460,"position":5},"title":"El Candombe &#8211; Mostra Fotogr\u00e1fica de Lisandro Moura","author":"antropologia","date":"18\/04\/2018","format":false,"excerpt":"A mostra fotogr\u00e1fica visa aproximar a popula\u00e7\u00e3o bageense de uma importante manifesta\u00e7\u00e3o cultural e art\u00edstica do Uruguai: o Candombe.\u00a0As fotografias, de autoria de Lisandro Moura, foram produzidas no contexto dos desfiles dellamadas\u00a0do carnaval uruguaio de 2018, em Montevideo e Melo, e est\u00e3o organizadas de acordo com elementos fundamentais da cultura\u2026","rel":"","context":"Em &quot;Convite&quot;","block_context":{"text":"Convite","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/convite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/04\/mostra-cartaz-3.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/04\/mostra-cartaz-3.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/04\/mostra-cartaz-3.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/04\/mostra-cartaz-3.jpg?resize=700%2C400 2x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/posts\/4460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/users\/641"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/comments?post=4460"}],"version-history":[{"count":4,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/posts\/4460\/revisions"}],"predecessor-version":[{"id":4473,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/posts\/4460\/revisions\/4473"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/media?parent=4460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/categories?post=4460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/tags?post=4460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}