{"id":1789,"date":"2018-10-25T15:11:44","date_gmt":"2018-10-25T18:11:44","guid":{"rendered":"https:\/\/leppais.wordpress.com\/?p=1789"},"modified":"2018-10-25T15:11:44","modified_gmt":"2018-10-25T18:11:44","slug":"convite-mostra-de-filmes-etnograficos-os-seres-da-mata-e-sua-vida-como-pessoas","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/leppais\/2018\/10\/25\/convite-mostra-de-filmes-etnograficos-os-seres-da-mata-e-sua-vida-como-pessoas\/","title":{"rendered":"Convite: Mostra de Filmes Etnogr\u00e1ficos &#8211; Os seres da mata e sua vida como pessoas"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1790\" data-permalink=\"https:\/\/wp.ufpel.edu.br\/leppais\/2018\/10\/25\/convite-mostra-de-filmes-etnograficos-os-seres-da-mata-e-sua-vida-como-pessoas\/mostra-de-filmes-etnograficos-01\/\" data-orig-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?fit=1754%2C1240&amp;ssl=1\" data-orig-size=\"1754,1240\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Mostra de Filmes Etnograficos-01\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?fit=300%2C212&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?fit=584%2C413&amp;ssl=1\" class=\"alignnone size-large wp-image-1790\" src=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=584%2C413&#038;ssl=1\" alt=\"\" width=\"584\" height=\"413\" srcset=\"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?w=1754&amp;ssl=1 1754w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=300%2C212&amp;ssl=1 300w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=768%2C543&amp;ssl=1 768w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=1024%2C724&amp;ssl=1 1024w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?resize=424%2C300&amp;ssl=1 424w, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/10\/mostra-de-filmes-etnograficos-01.jpg?w=1168&amp;ssl=1 1168w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":641,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-1789","post","type-post","status-publish","format-standard","hentry","category-convite"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/payVYo-sR","jetpack-related-posts":[{"id":3212,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2020\/07\/21\/convite-iii-mostra-arandu-de-filmes-etnograficos-2020\/","url_meta":{"origin":1789,"position":0},"title":"Convite &#8211; III MOSTRA ARANDU DE FILMES ETNOGRAFICOS 2020","author":"antropologia","date":"21\/07\/2020","format":false,"excerpt":"III Mostra Arandu de Filmes Etnogr\u00e1ficos 2020 \"Antropologia e Sociedade - Compartilhando Saberes\" Inscri\u00e7\u00f5es abertas pelo link at\u00e9 o dia 31\/08 Aguardamos sua inscri\u00e7\u00e3o! Formul\u00e1rio https:\/\/forms.gle\/77pnHaaRyREYKTW18 Links para as Mostras anteriores: https:\/\/arandumostra.wordpress.com\/ Link para nossa p\u00e1gina eletr\u00f4nica: https:\/\/avaedoc.blog\/ Mais informa\u00e7\u00f5es (PDF)","rel":"","context":"Em &quot;Convite&quot;","block_context":{"text":"Convite","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/convite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2020\/07\/arandu.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2020\/07\/arandu.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2020\/07\/arandu.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2020\/07\/arandu.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2020\/07\/arandu.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1849,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2018\/11\/21\/convite-mostra-de-filmes-etnograficos-com-o-filme-voz-das-mulheres-indigenas\/","url_meta":{"origin":1789,"position":1},"title":"Convite: Mostra de Filmes Etnogr\u00e1ficos com o filme &#8220;Voz das Mulheres Ind\u00edgenas&#8221;","author":"antropologia","date":"21\/11\/2018","format":false,"excerpt":"","rel":"","context":"Em &quot;Convite&quot;","block_context":{"text":"Convite","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/convite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/11\/2018-10-23-mostra-de-filmes-etnograficos-01.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1570,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2018\/06\/07\/iii-mostra-de-filmes-etnograficos\/","url_meta":{"origin":1789,"position":2},"title":"III Mostra de Filmes Etnogr\u00e1ficos","author":"antropologia","date":"07\/06\/2018","format":false,"excerpt":"","rel":"","context":"Em &quot;Atividades&quot;","block_context":{"text":"Atividades","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/atividades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/06\/iii-mostra-de-filmes-etnograficos_v6.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/06\/iii-mostra-de-filmes-etnograficos_v6.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/06\/iii-mostra-de-filmes-etnograficos_v6.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/06\/iii-mostra-de-filmes-etnograficos_v6.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2018\/06\/iii-mostra-de-filmes-etnograficos_v6.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3845,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2023\/08\/15\/17-ago-2023-3a-sessao-mostra-premio-pierre-verger\/","url_meta":{"origin":1789,"position":3},"title":"17 AGO 2023 \u2013 3\u00aa Sess\u00e3o Mostra Pr\u00eamio Pierre Verger","author":"antropologia","date":"15\/08\/2023","format":false,"excerpt":"Segue abaixo os respectivos links para Mostra Itinerante de Filmes Etnogr\u00e1ficos Pr\u00eamio Pierre Verger \/ edi\u00e7\u00e3o 2022. Link para inscri\u00e7\u00e3o: https:\/\/forms.gle\/HnxgUTByvnWYDgMw8 Link do canal do LABOME e do LEPPAIS onde ser\u00e1 transmitido: https:\/\/youtube.com\/@LabomeVisualidades https:\/\/www.youtube.com\/@leppais\/streams Al\u00e1gbed\u00e9 Do ferro-velho ao terreiro, Z\u00e9 Diabo forja deuses em sua oficina por meio do caminho\u2026","rel":"","context":"Em &quot;Convite&quot;","block_context":{"text":"Convite","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/convite\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2023\/08\/Cartaz-PPV2023-cineufpel-SESSAO-17AGO.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2023\/08\/Cartaz-PPV2023-cineufpel-SESSAO-17AGO.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2023\/08\/Cartaz-PPV2023-cineufpel-SESSAO-17AGO.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2023\/08\/Cartaz-PPV2023-cineufpel-SESSAO-17AGO.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2023\/08\/Cartaz-PPV2023-cineufpel-SESSAO-17AGO.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4460,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/21\/1a-mostra-antropoetica-de-filmes-etnograficos\/","url_meta":{"origin":1789,"position":4},"title":"1\u00aa Mostra Antropo\u00e9tica de Filmes Etnogr\u00e1ficos","author":"antropologia","date":"21\/11\/2025","format":false,"excerpt":"Em sua primeira edi\u00e7\u00e3o, esta Mostra conta com exibi\u00e7\u00e3o de filmes etnogr\u00e1ficos multissituada e debates online, estreitando as conex\u00f5es entre realizadores no campo da antropologia. O evento conta com a participa\u00e7\u00e3o das seguintes universidades e laborat\u00f3rios: Laborat\u00f3rio de Ensino, Pesquisa e Produ\u00e7\u00e3o em Antropologia da Imagem e do Som (LEPPAIS\/UFPel),\u2026","rel":"","context":"Em &quot;Not\u00edcias&quot;","block_context":{"text":"Not\u00edcias","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/noticias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?resize=700%2C400 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/1.png?resize=1050%2C600 3x"},"classes":[]},{"id":4474,"url":"https:\/\/wp.ufpel.edu.br\/leppais\/2025\/11\/28\/1a-mostra-antropoeticas-de-filmes-etnograficos-no-cehus\/","url_meta":{"origin":1789,"position":5},"title":"1\u00aa Mostra Antropo\u00e9ticas de Filmes Etnogr\u00e1ficos no Cehus","author":"antropologia","date":"28\/11\/2025","format":false,"excerpt":"\u00a0 No dia 27 de Novembro de 2025, ocorreu a 1\u00aa Mostra Antropo\u00e9ticas de Filmes Etnogr\u00e1ficos, no campus do Cehus da Ufpel. A mostra ocorreu das 14h \u00e0s 19h presencial e online em conjunto a parceiros, tendo direito at\u00e9 a pipoca para ver a mostra. Os filmes foram seguidos por\u2026","rel":"","context":"Em &quot;Atividades&quot;","block_context":{"text":"Atividades","link":"https:\/\/wp.ufpel.edu.br\/leppais\/category\/atividades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/wp.ufpel.edu.br\/leppais\/files\/2025\/11\/IMG-20251027-WA0034.jpg?resize=1400%2C800 4x"},"classes":[]}],"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/posts\/1789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/users\/641"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/comments?post=1789"}],"version-history":[{"count":0,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/posts\/1789\/revisions"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/media?parent=1789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/categories?post=1789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/leppais\/wp-json\/wp\/v2\/tags?post=1789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}