{"id":3477,"date":"2022-05-11T17:08:02","date_gmt":"2022-05-11T20:08:02","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/ib\/?p=3477"},"modified":"2022-05-11T17:29:03","modified_gmt":"2022-05-11T20:29:03","slug":"professora-aposentada-do-ib-na-presidencia-de-honra-72-congresso-brasileiro-de-botanica","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/ib\/2022\/05\/11\/professora-aposentada-do-ib-na-presidencia-de-honra-72-congresso-brasileiro-de-botanica\/","title":{"rendered":"Professora  do IB na Presid\u00eancia de Honra do 72 Congresso Brasileiro de Bot\u00e2nica"},"content":{"rendered":"<p style=\"text-align: justify;\">A professora Leila de F\u00e1tima Nogueira Macias do Departamento de Bot\u00e2nica\/Instituto de Biologia, recentemente aposentada, \u00e9 a Presidente de Honra do <strong>72 Congresso Brasileiro de Bot\u00e2nica<\/strong> que ser\u00e1 realizado de 24 a 28 de outubro vindouro com palestras <em>on line<\/em>. <em>A tem\u00e1tica do Congresso ser\u00e1 Bot\u00e2nica: Para que e para quem? Desafios, Avan\u00e7os e Perspectivas na Sociedade Contempor\u00e2nea<\/em>. Parab\u00e9ns a professora Leila e sucesso na Comiss\u00e3o Organizadora do evento.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/wp.ufpel.edu.br\/ib\/files\/2022\/05\/WhatsApp-Image-2022-05-10-at-15.36.44.jpeg\"><img class=\"alignnone size-medium wp-image-3479\" src=\"https:\/\/wp.ufpel.edu.br\/ib\/files\/2022\/05\/WhatsApp-Image-2022-05-10-at-15.36.44-189x400.jpeg\" alt=\"\" width=\"189\" height=\"400\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A professora Leila de F\u00e1tima Nogueira Macias do Departamento de Bot\u00e2nica\/Instituto de Biologia, recentemente aposentada, \u00e9 a Presidente de Honra do 72 Congresso Brasileiro de Bot\u00e2nica que ser\u00e1 realizado de 24 a 28 de outubro vindouro com palestras on line. A tem\u00e1tica do Congresso ser\u00e1 Bot\u00e2nica: Para que e para quem? Desafios, Avan\u00e7os e Perspectivas [&hellip;]<\/p>\n","protected":false},"author":488,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-3477","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6S2gY-U5","_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/ib\/wp-json\/wp\/v2\/posts\/3477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/ib\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/ib\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ib\/wp-json\/wp\/v2\/users\/488"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ib\/wp-json\/wp\/v2\/comments?post=3477"}],"version-history":[{"count":3,"href":"https:\/\/wp.ufpel.edu.br\/ib\/wp-json\/wp\/v2\/posts\/3477\/revisions"}],"predecessor-version":[{"id":3482,"href":"https:\/\/wp.ufpel.edu.br\/ib\/wp-json\/wp\/v2\/posts\/3477\/revisions\/3482"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/ib\/wp-json\/wp\/v2\/media?parent=3477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ib\/wp-json\/wp\/v2\/categories?post=3477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/ib\/wp-json\/wp\/v2\/tags?post=3477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}