{"id":148,"date":"2020-05-09T15:36:16","date_gmt":"2020-05-09T18:36:16","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/geuam\/?p=148"},"modified":"2020-05-09T15:36:35","modified_gmt":"2020-05-09T18:36:35","slug":"o-geuam-publica-edital-de-chamada-para-bolsa-de-extensao-na-area-de-judicializacao-de-medicamentos","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/geuam\/2020\/05\/09\/o-geuam-publica-edital-de-chamada-para-bolsa-de-extensao-na-area-de-judicializacao-de-medicamentos\/","title":{"rendered":"O GEUAM publica edital de CHAMADA para Bolsa de Extens\u00e3o na \u00e1rea de Judicializa\u00e7\u00e3o de Medicamentos"},"content":{"rendered":"<p>A todos alunos interessados, o GEUAM publica edital para Bolsa de Extens\u00e3o na \u00e1rea de Judicializa\u00e7\u00e3o de Medicamentos. Venha participar de atividades nesta importante \u00e1rea da profiss\u00e3o de Farmac\u00eautico.<\/p>\n<p>As inscri\u00e7\u00f5es s\u00e3o s\u00f3 at\u00e9 dia 12.05.2020 !<\/p>\n<p>Para maiores detalhes clique no link abaixo.<\/p>\n<p><a href=\"https:\/\/wp.ufpel.edu.br\/geuam\/files\/2020\/05\/Edital-de-sele\u00e7\u00e3o-2020.pdf\">Edital de sele\u00e7\u00e3o 2020<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A todos alunos interessados, o GEUAM publica edital para Bolsa de Extens\u00e3o na \u00e1rea de Judicializa\u00e7\u00e3o de Medicamentos. Venha participar de atividades nesta importante \u00e1rea da profiss\u00e3o de Farmac\u00eautico. As inscri\u00e7\u00f5es s\u00e3o s\u00f3 at\u00e9 dia 12.05.2020 ! Para maiores detalhes clique no link abaixo. Edital de sele\u00e7\u00e3o 2020<\/p>\n","protected":false},"author":962,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-148","post","type-post","status-publish","format-standard","hentry","category-noticias"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/geuam\/wp-json\/wp\/v2\/posts\/148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/geuam\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/geuam\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/geuam\/wp-json\/wp\/v2\/users\/962"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/geuam\/wp-json\/wp\/v2\/comments?post=148"}],"version-history":[{"count":1,"href":"https:\/\/wp.ufpel.edu.br\/geuam\/wp-json\/wp\/v2\/posts\/148\/revisions"}],"predecessor-version":[{"id":151,"href":"https:\/\/wp.ufpel.edu.br\/geuam\/wp-json\/wp\/v2\/posts\/148\/revisions\/151"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/geuam\/wp-json\/wp\/v2\/media?parent=148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/geuam\/wp-json\/wp\/v2\/categories?post=148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/geuam\/wp-json\/wp\/v2\/tags?post=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}