{"id":2733,"date":"2024-08-28T15:34:22","date_gmt":"2024-08-28T18:34:22","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/?p=2733"},"modified":"2024-08-28T15:34:22","modified_gmt":"2024-08-28T18:34:22","slug":"projeto-de-extensao-comunicacao-organizacional-e-comunicacao-publica-para-o-curso-de-gestao-publica-seleciona-participantes-voluntariosas","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/2024\/08\/28\/projeto-de-extensao-comunicacao-organizacional-e-comunicacao-publica-para-o-curso-de-gestao-publica-seleciona-participantes-voluntariosas\/","title":{"rendered":"Projeto de Extens\u00e3o &#8220;Comunica\u00e7\u00e3o organizacional e comunica\u00e7\u00e3o p\u00fablica para o Curso de Gest\u00e3o P\u00fablica&#8221; seleciona participantes volunt\u00e1rios(as)"},"content":{"rendered":"<p style=\"text-align: justify;\">O Projeto de Extens\u00e3o &#8220;Comunica\u00e7\u00e3o organizacional e comunica\u00e7\u00e3o p\u00fablica para o Curso de Gest\u00e3o P\u00fablica&#8221;, coordenado pela Professora Caroline Casali, torna p\u00fablico o edital de sele\u00e7\u00e3o de novos(as) participantes volunt\u00e1rios(as).<\/p>\n<p style=\"text-align: justify;\">As inscri\u00e7\u00f5es est\u00e3o abertas para estudantes de qualquer Curso do Centro de Ci\u00eancias S\u00f3cio-organizacionais, com exig\u00eancia de disponibilidade m\u00ednima de 10 horas semanais para atividades do Projeto. O per\u00edodo de inscri\u00e7\u00f5es vai de <strong>28 de agosto a 04 de setembro,\u00a0<\/strong>pelo email carolcasali@gmail.com.<\/p>\n<p style=\"text-align: justify;\">Informa\u00e7\u00f5es completas aqui: <a href=\"https:\/\/wp.ufpel.edu.br\/gestaopublica\/files\/2024\/08\/EDITAL_DE_SELECAO_DE_EXTENSIONISTA_VOLUNTARIO_assinado.pdf\">EDITAL_DE_SELECAO_DE_EXTENSIONISTA_VOLUNTARIO_assinado<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Projeto de Extens\u00e3o &#8220;Comunica\u00e7\u00e3o organizacional e comunica\u00e7\u00e3o p\u00fablica para o Curso de Gest\u00e3o P\u00fablica&#8221;, coordenado pela Professora Caroline Casali, torna p\u00fablico o edital de sele\u00e7\u00e3o de novos(as) participantes volunt\u00e1rios(as). As inscri\u00e7\u00f5es est\u00e3o abertas para estudantes de qualquer Curso do Centro de Ci\u00eancias S\u00f3cio-organizacionais, com exig\u00eancia de disponibilidade m\u00ednima de 10 horas semanais para atividades &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wp.ufpel.edu.br\/gestaopublica\/2024\/08\/28\/projeto-de-extensao-comunicacao-organizacional-e-comunicacao-publica-para-o-curso-de-gestao-publica-seleciona-participantes-voluntariosas\/\">Continue lendo<\/a><\/p>\n","protected":false},"author":250,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[18],"tags":[],"class_list":["post-2733","post","type-post","status-publish","format-standard","hentry","category-noticias","item-wrap"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6QO4J-I5","_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/wp-json\/wp\/v2\/posts\/2733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/wp-json\/wp\/v2\/users\/250"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/wp-json\/wp\/v2\/comments?post=2733"}],"version-history":[{"count":1,"href":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/wp-json\/wp\/v2\/posts\/2733\/revisions"}],"predecessor-version":[{"id":2736,"href":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/wp-json\/wp\/v2\/posts\/2733\/revisions\/2736"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/wp-json\/wp\/v2\/media?parent=2733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/wp-json\/wp\/v2\/categories?post=2733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/gestaopublica\/wp-json\/wp\/v2\/tags?post=2733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}