{"id":49020,"count":1,"description":"","link":"https:\/\/wp.ufpel.edu.br\/daee\/tag\/divulgacao\/","name":"Divulga\u00e7\u00e3o","slug":"divulgacao","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/daee\/wp-json\/wp\/v2\/tags\/49020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/daee\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/daee\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wp.ufpel.edu.br\/daee\/wp-json\/wp\/v2\/posts?tags=49020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}