{"id":2888,"date":"2026-01-29T15:20:22","date_gmt":"2026-01-29T18:20:22","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/comex\/?p=2888"},"modified":"2026-01-29T15:32:33","modified_gmt":"2026-01-29T18:32:33","slug":"estudante-de-comercio-exterior-retorna-ao-remar-para-o-futuro-e-assina-contrato-como-atleta-profissional","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/comex\/2026\/01\/29\/estudante-de-comercio-exterior-retorna-ao-remar-para-o-futuro-e-assina-contrato-como-atleta-profissional\/","title":{"rendered":"Estudante de Com\u00e9rcio Exterior retorna ao Remar para o Futuro e assina contrato como atleta profissional"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: justify;\">Na sexta-feira (16), a estudante do Curso de Com\u00e9rcio Exterior <strong>Evelen da Silva Cardoso<\/strong> oficializou seu retorno ao projeto Remar para o Futuro, assinando contrato para representar novamente o projeto pelotense em competi\u00e7\u00f5es de remo. A cerim\u00f4nia de assinatura aconteceu na sede campestre do Centro Portugu\u00eas e reuniu o presidente Eduardo Gil Carreira, o coordenador geral do projeto, professor Fabr\u00edcio Boscolo, o vice-reitor da Universidade Federal de Pelotas, professor Eraldo Pinheiro, al\u00e9m de outros membros da equipe.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2898 alignleft\" src=\"https:\/\/wp.ufpel.edu.br\/comex\/files\/2026\/01\/WhatsApp-Image-2026-01-29-at-15.30.21-e1769711542639-400x275.jpeg\" alt=\"\" width=\"400\" height=\"275\" srcset=\"https:\/\/wp.ufpel.edu.br\/comex\/files\/2026\/01\/WhatsApp-Image-2026-01-29-at-15.30.21-e1769711542639-400x275.jpeg 400w, https:\/\/wp.ufpel.edu.br\/comex\/files\/2026\/01\/WhatsApp-Image-2026-01-29-at-15.30.21-e1769711542639.jpeg 720w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Evelen come\u00e7ou sua jornada no esporte em 2015, permanecendo at\u00e9 2018 no Remar para o Futuro. Sua carreira inclui passagem pelo Flamengo, uma das principais pot\u00eancias do remo brasileiro. Em 2023, transferiu-se para o Gr\u00eamio N\u00e1utico Uni\u00e3o, clube que representou at\u00e9 2025.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Natural de Pelotas, a atleta construiu um curr\u00edculo impressionante: multimedalhista estadual, 17 vezes campe\u00e3 brasileira e seis vezes medalhista sul-americana. Evelen tamb\u00e9m teve a honra de representar o Brasil no Mundial Sub-23 e foi agraciada com a Medalha M\u00e9rito Esportivo em 2023 e 2025.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Emocionada, Evelen compartilhou os motivos que a trouxeram de volta: \u201cComo alguns devem saber, meu in\u00edcio no esporte foi em outubro de 2015, aqui mesmo neste clube. Foi aqui que me desenvolvi, aprendi a ser atleta e, muito al\u00e9m disso, me formei como cidad\u00e3. Muita coisa aconteceu nesses dez anos, e sou muito grata a Deus e \u00e0 minha fam\u00edlia por todo o apoio desde o in\u00edcio. Nem todos sabem, mas ap\u00f3s o acidente em 2024, eu e meu marido nos mudamos para c\u00e1 com uma miss\u00e3o: retornar para auxiliar no projeto e tentar retribuir, repassando aos nossos alunos tudo o que aprendemos com o nosso amado e eterno Oguener. O ano de 2025 me fez recalcular a rota para 2026 e entender que era hora de retornar de fato para a minha casa. Hoje me sinto realizada e muito feliz por estar de volta, pronta para dar mais um passo, continuar auxiliando nossos alunos \u2013 que hoje tamb\u00e9m s\u00e3o meus colegas de equipe \u2013 e desejo que este ano seja de muitas conquistas para todos n\u00f3s\u201d.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Al\u00e9m de seu brilhantismo no remo, Evelen se destaca academicamente. Em 2024, recebeu o Pr\u00eamio de Destaque do XII Congresso de Extens\u00e3o e Cultura, durante a 11\u00aa Semana Integrada de Inova\u00e7\u00e3o, Ensino, Pesquisa e Extens\u00e3o (SIIEPE). Sua trajet\u00f3ria \u00e9 motivo de orgulho para o Curso de Com\u00e9rcio Exterior e um exemplo inspirador de como \u00e9 poss\u00edvel unir excel\u00eancia acad\u00eamica, esporte de alto rendimento e compromisso com a transforma\u00e7\u00e3o social.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na sexta-feira (16), a estudante do Curso de Com\u00e9rcio Exterior Evelen da Silva Cardoso oficializou seu retorno ao projeto Remar para o Futuro, assinando contrato para representar novamente o projeto pelotense em competi\u00e7\u00f5es de remo. A cerim\u00f4nia de assinatura aconteceu na sede campestre do Centro Portugu\u00eas e reuniu o presidente Eduardo Gil Carreira, o coordenador &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/wp.ufpel.edu.br\/comex\/2026\/01\/29\/estudante-de-comercio-exterior-retorna-ao-remar-para-o-futuro-e-assina-contrato-como-atleta-profissional\/\">Continue lendo<\/a><\/p>\n","protected":false},"author":1252,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2888","post","type-post","status-publish","format-standard","hentry","category-noticias","item-wrap"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/comex\/wp-json\/wp\/v2\/posts\/2888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/comex\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/comex\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/comex\/wp-json\/wp\/v2\/users\/1252"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/comex\/wp-json\/wp\/v2\/comments?post=2888"}],"version-history":[{"count":2,"href":"https:\/\/wp.ufpel.edu.br\/comex\/wp-json\/wp\/v2\/posts\/2888\/revisions"}],"predecessor-version":[{"id":2899,"href":"https:\/\/wp.ufpel.edu.br\/comex\/wp-json\/wp\/v2\/posts\/2888\/revisions\/2899"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/comex\/wp-json\/wp\/v2\/media?parent=2888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/comex\/wp-json\/wp\/v2\/categories?post=2888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/comex\/wp-json\/wp\/v2\/tags?post=2888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}