{"id":306,"date":"2011-05-02T11:44:04","date_gmt":"2011-05-02T14:44:04","guid":{"rendered":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/?p=306"},"modified":"2011-05-09T12:11:20","modified_gmt":"2011-05-09T15:11:20","slug":"inscricoes-para-as-jornadas-pedagogicas-das-ciencias-sociais","status":"publish","type":"post","link":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/2011\/05\/02\/inscricoes-para-as-jornadas-pedagogicas-das-ciencias-sociais\/","title":{"rendered":"Abertas as inscri\u00e7\u00f5es para as Jornadas Pedag\u00f3gicas das Ci\u00eancias Sociais"},"content":{"rendered":"<p>Est\u00e3o abertas, desde o dia 02\/05, junto \u00e0 secretaria do Instituto de Sociologia e Pol\u00edtica, as inscri\u00e7\u00f5es para as Jornadas Pedag\u00f3gicas das Ci\u00eancias Sociais. Destinado aos professores, estudantes e funcion\u00e1rios que atuam no Curso de Ci\u00eancias Sociais e tendo como objetivo discutir a reforma do projeto pol\u00edtico pedag\u00f3gico, o evento ser\u00e1 realizado de 09 a 13 de maio, sempre \u00e0s 19 horas, no Audit\u00f3rio da Faculdade de Direito. Maiores informa\u00e7\u00f5es, voc\u00ea pode obter junto \u00e0 secretaria do Instituto de Sociologia e Pol\u00edtica. Fone: 32845542. <\/p>\n<p>Abaixo voc\u00ea confere a <strong>programa\u00e7\u00e3o do evento<\/strong>:<\/p>\n<p><strong>Dia 09\/05 &#8211; Segunda-feira<\/strong><br \/>\n17:00 horas &#8211; Atividade cultural<br \/>\n                   Sess\u00e3o de cinema: exibi\u00e7\u00e3o de document\u00e1rio <a href='https:\/\/wp.ufpel.edu.br\/cienciassociais\/files\/2011\/05\/SINOPSE-DO-DOCUMENT\u00c1RIO-HOME.doc'>HOME<\/a>.<br \/>\nLocal: Sala de Cinema do Col\u00e9gio S\u00e3o Jos\u00e9<\/p>\n<p>19:00 horas &#8211; Sess\u00e3o de Abertura<br \/>\n19:30 horas &#8211; Mesa Redonda: <strong>O campo de atua\u00e7\u00e3o profissional e a forma\u00e7\u00e3o dos cientistas sociais no Brasil.<\/strong><br \/>\nMediador: Prof. Francisco E. B. Vargas<br \/>\nDebatedores: Prof. Daniel de Mendon\u00e7a (ISP), Prof. L\u00e9o Peixoto (ISP), Prof. Rog\u00e9rio R. G. da Rosa (ICH).<\/p>\n<p><strong>Dia 10\/05 &#8211; Ter\u00e7a-feira<\/strong><\/p>\n<p>19:00 horas &#8211; Mesa Redonda: <strong>Projeto pedag\u00f3gico, curr\u00edculo e as diretrizes curriculares para os cursos de ci\u00eancias sociais.<\/strong><br \/>\nMediador: Prof. Francisco E. B. Vargas<br \/>\nDebatedores: Profa. Eliana P\u00f3voas de Brito (PRG), Profa. Maria Manuela A. Garcia (FaE).<\/p>\n<p><strong>Dia 11\/05 &#8211; Quarta-feira<\/strong><\/p>\n<p>19:00 horas &#8211; Painel e Debate: <strong>Diagn\u00f3stico dos Cursos de Ci\u00eancias Sociais da UFPel<\/strong><br \/>\nPainelistas: Prof. Francisco E. B. Vargas (Coordenador do Curso), Acad\u00eamico Gabriel Coelho (Ci\u00eancias Sociais Licenciatura) e Acad\u00eamica Darine Machado (Ci\u00eancias Sociais Bacharelado).<br \/>\nApresenta\u00e7\u00e3o da discuss\u00e3o de diagn\u00f3stico dos Grupos de Trabalho<\/p>\n<p><strong>Dia 12\/05 &#8211; Quinta-feira<\/strong><\/p>\n<p>19:00 horas &#8211; Painel e Debate: <strong>A reforma do projeto pol\u00edtico pedag\u00f3gico: apresenta\u00e7\u00e3o de propostas <\/strong><br \/>\nMediador: Prof. Francisco E. B. Vargas<br \/>\nApresenta\u00e7\u00e3o das propostas dos grupos de trabalho.<br \/>\nTemas de discuss\u00e3o: Estrutura curricular; os eixos curriculares e as metodologias; pr\u00e1ticas de ensino e est\u00e1gios; sistema de avalia\u00e7\u00e3o; estrutura f\u00edsica, recursos materiais e recursos humanos; as articula\u00e7\u00f5es<br \/>\nentre ensino, pesquisa e extens\u00e3o.<\/p>\n<p><strong>Dia 13\/05 &#8211; Sexta-feira<\/strong><\/p>\n<p>19:00 horas &#8211; Atividade cultural<\/p>\n<p>19:30 horas &#8211; Plen\u00e1ria de encerramento: Continua\u00e7\u00e3o do debate e encaminhamentos sobre a reforma do projeto pol\u00edtico pedag\u00f3gico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e3o abertas, desde o dia 02\/05, junto \u00e0 secretaria do Instituto de Sociologia e Pol\u00edtica, as inscri\u00e7\u00f5es para as Jornadas Pedag\u00f3gicas das Ci\u00eancias Sociais. Destinado aos professores, estudantes e funcion\u00e1rios que atuam no Curso de Ci\u00eancias Sociais e tendo como objetivo discutir a reforma do projeto pol\u00edtico pedag\u00f3gico, o evento ser\u00e1 realizado de 09 a [&hellip;]<\/p>\n","protected":false},"author":56,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-306","post","type-post","status-publish","format-standard","hentry","category-noticias"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/wp-json\/wp\/v2\/posts\/306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/wp-json\/wp\/v2\/comments?post=306"}],"version-history":[{"count":22,"href":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/wp-json\/wp\/v2\/posts\/306\/revisions"}],"predecessor-version":[{"id":308,"href":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/wp-json\/wp\/v2\/posts\/306\/revisions\/308"}],"wp:attachment":[{"href":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/wp-json\/wp\/v2\/media?parent=306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/wp-json\/wp\/v2\/categories?post=306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.ufpel.edu.br\/cienciassociais\/wp-json\/wp\/v2\/tags?post=306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}